{"id":4619,"date":"2026-01-12T15:32:08","date_gmt":"2026-01-12T15:32:08","guid":{"rendered":"https:\/\/mercadohogar.ca\/?post_type=product&#038;p=4619"},"modified":"2026-01-17T23:13:29","modified_gmt":"2026-01-17T23:13:29","slug":"cafetera-de-espresso-y-capuchino","status":"publish","type":"product","link":"https:\/\/mercadohogar.ca\/es\/product\/cafetera-de-espresso-y-capuchino\/","title":{"rendered":"Cafetera de espresso y capuchino"},"content":{"rendered":"<p>Prepara deliciosos espressos, capuchinos y lattes con calidad de barista en la comodidad de tu hogar con esta cafetera espresso manual de De&#8217;Longhi. Su avanzado sistema de capuchino mantiene la temperatura, por lo que no hay que esperar entre tazas. Consigue la espuma cremosa perfecta con el espumador manual que combina vapor y leche a la perfecci\u00f3n.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prepara deliciosos espressos, capuchinos y lattes con calidad de barista en la comodidad de tu hogar con esta cafetera espresso manual de De&#8217;Longhi. Su avanzado sistema de capuchino mantiene la&hellip;<\/p>\n","protected":false},"featured_media":2544,"template":"","meta":[],"product_brand":[],"product_cat":[988],"product_tag":[],"class_list":{"0":"post-4619","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-electrodomesticos","7":"product_shipping_class-aerovaradero-general","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/product\/4619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/product\/4619\/revisions"}],"predecessor-version":[{"id":4886,"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/product\/4619\/revisions\/4886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/media\/2544"}],"wp:attachment":[{"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/media?parent=4619"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/product_brand?post=4619"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/product_cat?post=4619"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mercadohogar.ca\/es\/wp-json\/wp\/v2\/product_tag?post=4619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}